{"id":3835,"date":"2026-07-15T13:57:03","date_gmt":"2026-07-15T11:57:03","guid":{"rendered":"https:\/\/ecolesainteanne-baud.com\/?p=3835"},"modified":"2026-07-15T13:57:03","modified_gmt":"2026-07-15T11:57:03","slug":"sortie-scolaire-des-maternelles","status":"publish","type":"post","link":"https:\/\/ecolesainteanne-baud.com\/index.php\/2026\/07\/15\/sortie-scolaire-des-maternelles\/","title":{"rendered":"Sortie scolaire des Maternelles"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3830\" src=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0006-768x1024.jpg\" alt=\"\" class=\"wp-image-3830\" srcset=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0006-768x1024.jpg 768w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0006-225x300.jpg 225w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0006-1152x1536.jpg 1152w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0006.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3829\" src=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0005-768x1024.jpg\" alt=\"\" class=\"wp-image-3829\" srcset=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0005-768x1024.jpg 768w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0005-225x300.jpg 225w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0005-1152x1536.jpg 1152w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0005.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3828\" src=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0004-768x1024.jpg\" alt=\"\" class=\"wp-image-3828\" srcset=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0004-768x1024.jpg 768w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0004-225x300.jpg 225w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0004-1152x1536.jpg 1152w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0004.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3827\" src=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0003-768x1024.jpg\" alt=\"\" class=\"wp-image-3827\" srcset=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0003-768x1024.jpg 768w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0003-225x300.jpg 225w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0003-1152x1536.jpg 1152w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0003.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3826\" src=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0002-1024x768.jpg\" alt=\"\" class=\"wp-image-3826\" srcset=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0002-1024x768.jpg 1024w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0002-300x225.jpg 300w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0002-768x576.jpg 768w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0002-1536x1152.jpg 1536w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0002.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3825\" src=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0001-1024x768.jpg\" alt=\"\" class=\"wp-image-3825\" srcset=\"https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0001-1024x768.jpg 1024w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0001-300x225.jpg 300w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0001-768x576.jpg 768w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0001-1536x1152.jpg 1536w, https:\/\/ecolesainteanne-baud.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0001.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5],"tags":[],"class_list":["post-3835","post","type-post","status-publish","format-standard","hentry","category-cycle-1","category-vie-des-classes","entry"],"_links":{"self":[{"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/posts\/3835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/comments?post=3835"}],"version-history":[{"count":1,"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/posts\/3835\/revisions"}],"predecessor-version":[{"id":3836,"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/posts\/3835\/revisions\/3836"}],"wp:attachment":[{"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/media?parent=3835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/categories?post=3835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolesainteanne-baud.com\/index.php\/wp-json\/wp\/v2\/tags?post=3835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}